{"id":58497,"date":"2024-04-26T09:52:54","date_gmt":"2024-04-26T07:52:54","guid":{"rendered":"https:\/\/www.intralogistik-messen.de\/products\/double-axes-gate\/"},"modified":"2026-05-13T13:19:57","modified_gmt":"2026-05-13T11:19:57","slug":"axes-gate","status":"publish","type":"products","link":"https:\/\/www.intralogistik-messen.de\/en\/products\/axes-gate\/","title":{"rendered":"Axes gate"},"content":{"rendered":"<p>AXES GATE ist eine Sicherheitst\u00fcr f\u00fcr Fallschutzl\u00f6sungen und zur Sicherung des Zugangs zu Maschinenanlagen. Die ideale L\u00f6sung, wenn Sie auf Sicherheit, Nachhaltigkeit und Kosteneffizienz setzen.<\/p>\n<p>Die AXES GATE T\u00fcren werden seit 20 Jahren weltweit unter h\u00e4rtesten und anspruchsvollsten Bedingungen eingesetzt, u. a. in der chemischen Industrie und auf Offshore-Bohrplattformen. Sie widerstehen rauen Witterungsbedingungen, extrem salzhaltigen Umgebungen und stark korrosiven Chemikalien. Design, Konstruktion und Eigenschaften der Sicherheitst\u00fcr erm\u00f6glichen den vielf\u00e4ltigen Einsatz in praktisch allen Branchen.<\/p>\n<p>Die AXES GATE Sicherheitst\u00fcr besteht aus Boplans High Impact Thermoplastic Engineered Polymer (HI-TEP) und bietet un\u00fcbertroffene Lebensdauer. Das Scharnier wurde in \u00fcber 150.000 Schlie\u00dfzyklen getestet. Das entspricht 20 \u00d6ffnungs- und Schlie\u00dfvorg\u00e4ngen pro Tag in einem Zeitraum von 20 Jahren. Dank des innovativen Designs erfordert die Montage nur wenig Werkzeug und Arbeitsaufwand. Die AXES GATE T\u00fcr kann in zwei Richtungen ge\u00f6ffnet werden und l\u00e4sst sich einfach an die gew\u00fcnschte Breite anpassen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AXES GATE ist eine Sicherheitst\u00fcr f\u00fcr Fallschutzl\u00f6sungen und zur Sicherung des Zugangs zu Maschinenanlagen. Die ideale L\u00f6sung, wenn Sie auf Sicherheit, Nachhaltigkeit und Kosteneffizienz setzen. Die AXES GATE T\u00fcren werden seit 20 Jahren weltweit unter h\u00e4rtesten und anspruchsvollsten Bedingungen eingesetzt, u. a. in der chemischen Industrie und auf Offshore-Bohrplattformen. Sie widerstehen rauen Witterungsbedingungen, extrem salzhaltigen [&hellip;]<\/p>\n","protected":false},"featured_media":58498,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_api_id":"229293","_exhibitors":["52164","52130"],"footnotes":""},"tags":[],"edition":[430],"product-category":[],"class_list":["post-58497","products","type-products","status-publish","has-post-thumbnail","hentry","edition-logistics-automation-hamburg-2024"],"_links":{"self":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/58497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":4,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/58497\/revisions"}],"predecessor-version":[{"id":68410,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/58497\/revisions\/68410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media\/58498"}],"wp:attachment":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media?parent=58497"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/tags?post=58497"},{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/edition?post=58497"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/product-category?post=58497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}