{"id":58487,"date":"2024-04-26T09:45:06","date_gmt":"2024-04-26T07:45:06","guid":{"rendered":"https:\/\/www.intralogistik-messen.de\/products\/neue-saulenschutz\/"},"modified":"2024-04-26T10:43:32","modified_gmt":"2024-04-26T08:43:32","slug":"neue-saeulenschutz","status":"publish","type":"products","link":"https:\/\/www.intralogistik-messen.de\/en\/products\/neue-saeulenschutz\/","title":{"rendered":"Neue S\u00e4ulenschutz"},"content":{"rendered":"<p>Unsere neuen S\u00e4ulensch\u00fctzer mit einer H\u00f6he von 19,7&#8243; (500 mm) gew\u00e4hrleisten den Schutz von S\u00e4ulen, an denen Feuerl\u00f6scher, Elektrok\u00e4sten oder \u00e4hnliche Produkte montiert sind. Diese aktualisierte Serie wird in den Durchmessern 20,5&#8243; (200 mm) und 24,4&#8243; (300 mm) in den Farben Signalgelb und Verkehrsrot erh\u00e4ltlich sein.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere neuen S\u00e4ulensch\u00fctzer mit einer H\u00f6he von 19,7&#8243; (500 mm) gew\u00e4hrleisten den Schutz von S\u00e4ulen, an denen Feuerl\u00f6scher, Elektrok\u00e4sten oder \u00e4hnliche Produkte montiert sind. Diese aktualisierte Serie wird in den Durchmessern 20,5&#8243; (200 mm) und 24,4&#8243; (300 mm) in den Farben Signalgelb und Verkehrsrot erh\u00e4ltlich sein.<\/p>\n","protected":false},"featured_media":58488,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_api_id":"229291","_exhibitors":["52164","52130"],"footnotes":""},"tags":[],"edition":[430],"product-category":[],"class_list":["post-58487","products","type-products","status-publish","has-post-thumbnail","hentry","edition-logistics-automation-hamburg-2024"],"_links":{"self":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/58487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":2,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/58487\/revisions"}],"predecessor-version":[{"id":58491,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/58487\/revisions\/58491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media\/58488"}],"wp:attachment":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media?parent=58487"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/tags?post=58487"},{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/edition?post=58487"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/product-category?post=58487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}