{"id":55879,"date":"2024-03-14T11:49:13","date_gmt":"2024-03-14T10:49:13","guid":{"rendered":"https:\/\/www.intralogistik-messen.de\/products\/teddy-pro-schutzprofile-zum-verhindern-von-verletzungen-oder-beschaedigungen\/"},"modified":"2024-04-26T10:43:31","modified_gmt":"2024-04-26T08:43:31","slug":"teddy-pro-schutzprofile-zum-verhindern-von-verletzungen-oder-beschaedigungen","status":"publish","type":"products","link":"https:\/\/www.intralogistik-messen.de\/en\/products\/teddy-pro-schutzprofile-zum-verhindern-von-verletzungen-oder-beschaedigungen\/","title":{"rendered":"TEDDY PRO: SCHUTZPROFILE ZUM VERHINDERN VON VERLETZUNGEN ODER BESCH\u00c4DIGUNGEN"},"content":{"rendered":"<p>TEDDY PRO ist ein flexibles Schutzprofil aus PU mit unz\u00e4hligen Anwendungsm\u00f6glichkeiten. Die Schutzprofile erm\u00f6glichen es Ihnen sehr einfach, Mitarbeiter vor Ecken oder scharfen Kanten zu sch\u00fctzen. Zus\u00e4tzlich sch\u00fctzen die Profile auch gegen Besch\u00e4digungen durch W\u00e4gen oder Trolleys. Auf diese Weise vermeiden Sie nicht nur Verletzungen Ihrer Mitarbeiter, sondern halten auch die Infrastruktur und Ihre Produkte frei von Dellen und Kratzern.<\/p>\n<p>Es stehen vier Modelle von je 1 m bzw. 2 m L\u00e4nge zur Verf\u00fcgung. Neben unserem flachen Modell (TEDDY PRO FL40) bieten wir drei Varianten f\u00fcr unterschiedliche Eckenprofile an: Ein rundes Modell, f\u00fcr die Befestigung an Ecken (TEDDY PRO AR25) oder Stangen (TEDDY PRO RR30), und ein dreieckiges Modell (TEDDY PRO EV19). Durch ihr gelb-schwarzes Muster springen die Profile sofort ins Auge und beugen allein dadurch schon Kollisionen vor. Die TEDDY PRO -Artikel sind einzeln erh\u00e4ltlich bzw. in Verkaufseinheiten zu je 5, 10 oder 50 St\u00fcck.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TEDDY PRO ist ein flexibles Schutzprofil aus PU mit unz\u00e4hligen Anwendungsm\u00f6glichkeiten. Die Schutzprofile erm\u00f6glichen es Ihnen sehr einfach, Mitarbeiter vor Ecken oder scharfen Kanten zu sch\u00fctzen. Zus\u00e4tzlich sch\u00fctzen die Profile auch gegen Besch\u00e4digungen durch W\u00e4gen oder Trolleys. Auf diese Weise vermeiden Sie nicht nur Verletzungen Ihrer Mitarbeiter, sondern halten auch die Infrastruktur und Ihre Produkte [&hellip;]<\/p>\n","protected":false},"featured_media":34065,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_api_id":"150693","_exhibitors":["52164","52130"],"footnotes":""},"tags":[],"edition":[430],"product-category":[],"class_list":["post-55879","products","type-products","status-publish","has-post-thumbnail","hentry","edition-logistics-automation-hamburg-2024"],"_links":{"self":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/55879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":1,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/55879\/revisions"}],"predecessor-version":[{"id":55885,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/55879\/revisions\/55885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media\/34065"}],"wp:attachment":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media?parent=55879"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/tags?post=55879"},{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/edition?post=55879"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/product-category?post=55879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}