{"id":54757,"date":"2024-02-12T16:00:35","date_gmt":"2024-02-12T15:00:35","guid":{"rendered":"https:\/\/www.intralogistik-messen.de\/products\/prolag-world-transport\/"},"modified":"2024-02-12T16:02:36","modified_gmt":"2024-02-12T15:02:36","slug":"prolag-world-transport","status":"publish","type":"products","link":"https:\/\/www.intralogistik-messen.de\/en\/products\/prolag-world-transport\/","title":{"rendered":"PROLAG World Transport"},"content":{"rendered":"<p>PPROLAG Transport ist die nat\u00fcrliche Erweiterung des Warenausgangs f\u00fcr Unternehmen mit eigenem Fuhrpark. Unsere Logistik-Experten haben das Tourenmanagement so konzipiert, dass der Weg vom Versandbahnhof bis zum Empf\u00e4nger unkompliziert in die Intralogistik integriert wird. Das System bietet zahlreiche praktische Features, die den Versand zum Zwischenlager oder dem Endkunden erheblich vereinfachen. Ausgehend von den vorliegenden Artikeldaten, weist die Software der Sendung automatisch die passende Tour zu. Dazu bietet die App verschiedene Quittierungsm\u00f6glichkeiten an \u2013 von der digitalen Signatur \u00fcber Mitarbeiterk\u00fcrzel bis hin zur Fotofunktion.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PPROLAG Transport ist die nat\u00fcrliche Erweiterung des Warenausgangs f\u00fcr Unternehmen mit eigenem Fuhrpark. Unsere Logistik-Experten haben das Tourenmanagement so konzipiert, dass der Weg vom Versandbahnhof bis zum Empf\u00e4nger unkompliziert in die Intralogistik integriert wird. Das System bietet zahlreiche praktische Features, die den Versand zum Zwischenlager oder dem Endkunden erheblich vereinfachen. Ausgehend von den vorliegenden Artikeldaten, [&hellip;]<\/p>\n","protected":false},"featured_media":43772,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_api_id":"164353","_exhibitors":["52165"],"footnotes":""},"tags":[],"edition":[431],"product-category":[],"class_list":["post-54757","products","type-products","status-publish","has-post-thumbnail","hentry","edition-logistics-automation-dortmund-2024"],"_links":{"self":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/54757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/types\/products"}],"version-history":[{"count":1,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/54757\/revisions"}],"predecessor-version":[{"id":54780,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/54757\/revisions\/54780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media\/43772"}],"wp:attachment":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media?parent=54757"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/tags?post=54757"},{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/edition?post=54757"},{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/product-category?post=54757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}