{"id":55115,"date":"2024-02-16T13:21:14","date_gmt":"2024-02-16T12:21:14","guid":{"rendered":"https:\/\/www.intralogistik-messen.de\/exhibitor\/bahr-modultechnik-gmbh\/"},"modified":"2024-06-05T12:50:11","modified_gmt":"2024-06-05T10:50:11","slug":"bahr-modultechnik-gmbh","status":"publish","type":"exhibitor","link":"https:\/\/www.intralogistik-messen.de\/en\/exhibitor\/bahr-modultechnik-gmbh\/","title":{"rendered":"Bahr Modultechnik GmbH"},"content":{"rendered":"<p>Die Bahr Modultechnik ist seit 1990 Ihr Experte in der Entwicklung und Fertigung von Linearachsen h\u00f6chster Qualit\u00e4t. Sie erhalten mit uns den passenden Partner bei der Auslegung des optimalen Systems. In partnerschaftlicher Zusammenarbeit erarbeiten wir gemeinsam Ihre ma\u00dfgeschneiderte L\u00f6sung vom Einzelteil bis zur Serienfertigung. Vom Einkauf bis hin zur Auslieferung wird darauf acht gegeben, Ihre Vorstellungen von einem guten Preis-Leistungs-Verh\u00e4ltnis  stets zu \u00fcbertreffen. Ihre Zufriedenheit ist unser Antrieb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Bahr Modultechnik ist seit 1990 Ihr Experte in der Entwicklung und Fertigung von Linearachsen h\u00f6chster Qualit\u00e4t. Sie erhalten mit uns den passenden Partner bei der Auslegung des optimalen Systems. In partnerschaftlicher Zusammenarbeit erarbeiten wir gemeinsam Ihre ma\u00dfgeschneiderte L\u00f6sung vom Einzelteil bis zur Serienfertigung. Vom Einkauf bis hin zur Auslieferung wird darauf acht gegeben, Ihre [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_api_id":"180207","_stand_number":"E14","_partner_id":"0efj7of68pl4i","_package_code":"00-EASY-EASYGO25-300","_website":"https:\/\/www.bahr-modultechnik.de\/","_email":"tobias.saecker@imiplc.com","_facebook":"","_linkedin":"","_twitter":"","_instagram":"","_zipcode":"31711","_town":"Luhden","_video_banner":"","_floorplan_url":"","footnotes":""},"edition":[430],"country":[93],"exhibitor-category":[442,454,441],"class_list":["post-55115","exhibitor","type-exhibitor","status-publish","hentry","edition-logistics-automation-hamburg-2024","country-de","exhibitor-category-automatisierungstechnik-17869","exhibitor-category-kommissionierungstechnik-17863","exhibitor-category-lagertechnik-17868","feature--stand-has-video-header","feature--stand-has-logo-shown"],"_logo":55214,"_cover_image":null,"_thumbnail_id":null,"_products":[],"_news":[],"_jobs":[],"_links":{"self":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/55115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor"}],"about":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/types\/exhibitor"}],"version-history":[{"count":1,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/55115\/revisions"}],"predecessor-version":[{"id":55213,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/55115\/revisions\/55213"}],"wp:attachment":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media?parent=55115"}],"wp:term":[{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/edition?post=55115"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/country?post=55115"},{"taxonomy":"exhibitor-category","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor-category?post=55115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}