{"id":54428,"date":"2024-01-26T15:51:01","date_gmt":"2024-01-26T14:51:01","guid":{"rendered":"https:\/\/www.intralogistik-messen.de\/exhibitor\/4am-robotics-gmbh\/"},"modified":"2024-08-06T12:53:26","modified_gmt":"2024-08-06T10:53:26","slug":"4am-robotics","status":"publish","type":"exhibitor","link":"https:\/\/www.intralogistik-messen.de\/en\/exhibitor\/4am-robotics\/","title":{"rendered":"4am Robotics"},"content":{"rendered":"<p>4am Robotics ist Spezialist f\u00fcr autonome mobile Roboter (AMR) f\u00fcr die Intralogistik. Produkt\u00fcbergreifende Technik und Software treffen bei 4am Robotics auf ein heterogenes Portfolio, das den Warenfluss flexibel, sicher und allzeit verf\u00fcgbar von Ende zu Ende automatisiert und Komplexit\u00e4t reduziert. Das Unternehmen bietet L\u00f6sungen vom autonomen Routenzug \u00fcber autonome mobile Cobots bis hin zum autonomen Gabelstapler. 4am Robotics wurde 2022 aus der Verbindung zweier Unternehmen gegr\u00fcndet und vereint langj\u00e4hrige Automatisierungskompetenz mit forschungsorientierten und innovativen Ans\u00e4tzen eines Frauenhofer Spin-offs.<br \/>\n4am Robotics ist ein Unternehmen der SCIO Automation Gruppe, die als internationale Unternehmensplattform Logistik- und Produktionsprozesse ganzheitlich automatisiert und mittlerweile mehr als 11 Unternehmensmarken an \u00fcber 35 Standorten weltweit zusammenbringt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>4am Robotics ist Spezialist f\u00fcr autonome mobile Roboter (AMR) f\u00fcr die Intralogistik. Produkt\u00fcbergreifende Technik und Software treffen bei 4am Robotics auf ein heterogenes Portfolio, das den Warenfluss flexibel, sicher und allzeit verf\u00fcgbar von Ende zu Ende automatisiert und Komplexit\u00e4t reduziert. Das Unternehmen bietet L\u00f6sungen vom autonomen Routenzug \u00fcber autonome mobile Cobots bis hin zum autonomen [&hellip;]<\/p>\n","protected":false},"featured_media":60284,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_api_id":"177591","_stand_number":"A06 - 4","_partner_id":"20bzhv85s1ndy","_package_code":"00-EASY-EASYGO25-400","_website":"https:\/\/www.4am-robotics.com","_email":"info@4am-robotics.com","_facebook":"","_linkedin":"https:\/\/www.linkedin.com\/company\/4am-robotics\/","_twitter":"","_instagram":"","_zipcode":"70771","_town":"Leinfelden-Echterdingen","_video_banner":"","_floorplan_url":"","footnotes":""},"edition":[431],"country":[93],"exhibitor-category":[435,448,436],"class_list":["post-54428","exhibitor","type-exhibitor","status-publish","has-post-thumbnail","hentry","edition-logistics-automation-dortmund-2024","country-de","exhibitor-category-automatisierungstechnik-17851","exhibitor-category-flurforderzeuge-und-zubehor-17841","exhibitor-category-smart-logistics-17853","feature--stand-has-extra-visibility","feature--stand-has-video-header","feature--stand-has-logo-shown"],"_logo":57084,"_cover_image":null,"_thumbnail_id":60284,"_products":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/57138"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/57129"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/57122"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/57113"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/57097"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/57086"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/57072"}],"_news":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/news\/57157"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/news\/57148"}],"_jobs":[],"_links":{"self":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/54428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor"}],"about":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/types\/exhibitor"}],"version-history":[{"count":3,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/54428\/revisions"}],"predecessor-version":[{"id":56814,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/54428\/revisions\/56814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media\/60284"}],"wp:attachment":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media?parent=54428"}],"wp:term":[{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/edition?post=54428"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/country?post=54428"},{"taxonomy":"exhibitor-category","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor-category?post=54428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}