{"id":52160,"date":"2023-10-12T15:43:02","date_gmt":"2023-10-12T13:43:02","guid":{"rendered":"https:\/\/www.intralogistik-messen.de\/exhibitor\/axelent-gmbh\/"},"modified":"2024-04-26T13:20:52","modified_gmt":"2024-04-26T11:20:52","slug":"axelent-gmbh","status":"publish","type":"exhibitor","link":"https:\/\/www.intralogistik-messen.de\/en\/exhibitor\/axelent-gmbh\/","title":{"rendered":"Axelent GmbH"},"content":{"rendered":"<p>Axelent ist ein schwedisches Unternehmen mit langj\u00e4hriger Erfahrung im Bereich Arbeitssicherheit. Schnelligkeit, Sicherheit, Service und intelligente L\u00f6sungen sind Schlagworte, die unsere gesamte Organisation und unser Gesch\u00e4ft kennzeichnen. Wir sind ein Partner mit umfassendem Wissen im Sicherheitsbereich und unsere Produkte werden weltweit in der Produktion und in Lagerumgebungen eingesetzt. Nat\u00fcrlich immer gem\u00e4\u00df den gesetzlichen Vorschriften.<\/p>\n<p>Unser Produktportfolio umfasst neben Maschinenschutz auch Lager- und Rammschutz und deckt dadurch einen Gro\u00dfteil an Arbeitssicherheitsma\u00dfnahmen und -bestimmungen ab.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Axelent ist ein schwedisches Unternehmen mit langj\u00e4hriger Erfahrung im Bereich Arbeitssicherheit. Schnelligkeit, Sicherheit, Service und intelligente L\u00f6sungen sind Schlagworte, die unsere gesamte Organisation und unser Gesch\u00e4ft kennzeichnen. Wir sind ein Partner mit umfassendem Wissen im Sicherheitsbereich und unsere Produkte werden weltweit in der Produktion und in Lagerumgebungen eingesetzt. Nat\u00fcrlich immer gem\u00e4\u00df den gesetzlichen Vorschriften. Unser [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_api_id":"165817","_stand_number":"D20-4","_partner_id":"27i7hs0dk0raf","_package_code":"00-EASY-EASYGO25-300","_website":"https:\/\/www.axelent.de","_email":"timo.reile@axelent.de","_facebook":"","_linkedin":"","_twitter":"","_instagram":"","_zipcode":"70597","_town":"Stuttgart","_video_banner":"","_floorplan_url":"","footnotes":""},"edition":[431],"country":[93],"exhibitor-category":[444,439,434,445,436],"class_list":["post-52160","exhibitor","type-exhibitor","status-publish","hentry","edition-logistics-automation-dortmund-2024","country-de","exhibitor-category-lager-und-betriebseinrichtungen-17847","exhibitor-category-lagerhilfsmittelteile-zubehoer-und-komponenten","exhibitor-category-lagertechnik-17846","exhibitor-category-logistische-dienstleistungen-services-17855","exhibitor-category-smart-logistics-17853","feature--stand-has-video-header","feature--stand-has-logo-shown"],"_logo":52427,"_cover_image":null,"_thumbnail_id":null,"_products":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/56984"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/56981"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/56978"}],"_news":[],"_jobs":[],"_links":{"self":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/52160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor"}],"about":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/types\/exhibitor"}],"version-history":[{"count":1,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/52160\/revisions"}],"predecessor-version":[{"id":52426,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/52160\/revisions\/52426"}],"wp:attachment":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media?parent=52160"}],"wp:term":[{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/edition?post=52160"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/country?post=52160"},{"taxonomy":"exhibitor-category","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor-category?post=52160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}