{"id":52159,"date":"2023-10-12T15:43:02","date_gmt":"2023-10-12T13:43:02","guid":{"rendered":"https:\/\/www.intralogistik-messen.de\/exhibitor\/andreas-laubner-gmbh\/"},"modified":"2023-11-29T09:55:15","modified_gmt":"2023-11-29T08:55:15","slug":"andreas-laubner-gmbh","status":"publish","type":"exhibitor","link":"https:\/\/www.intralogistik-messen.de\/en\/exhibitor\/andreas-laubner-gmbh\/","title":{"rendered":"Andreas Laubner GmbH"},"content":{"rendered":"<p>Als renommiertes Systemhaus f\u00fcr Auto-ID Solutions sch\u00f6pft die Andreas Laubner GmbH mit Sitz in Maxdorf (RLP) aus \u00fcber 25 Jahren Erfahrung in den Branchen Logistik und Industrie. Jahrzehntelange enge Partnerschaften mit zahlreichen Kunden aus ganz Europa unterstreichen unsere umfassenden Kompetenzen. Wir passen unsere Leistungen und Services individuell an unsere Kunden an &#8211; bei uns gibt es kein Schubladendenken. Unser vielseitiges Portfolio reicht von Hardware f\u00fcr Unternehmen mit Schwerpunkt auf den Branchen Transport und Logistik \u00fcber zahlreiche Dienstleistungen wie Funkausleuchtung, Integration von Soft- und Hardware-L\u00f6sungen in bestehende IT-Strukturen bis hin zu unseren speziellen Sonderl\u00f6sungen, passgenau auf die W\u00fcnsche unserer Kunden zugeschnitten.<\/p>\n<p>Ein essenzieller Wert der Andreas Laubner GmbH ist der technologische Fortschritt, gepaart mit h\u00f6chsten Qualit\u00e4tsanspr\u00fcchen \u2013 nat\u00fcrlich zertifiziert nach ISO9001:2015.<\/p>\n<p>Weitere Informationen: www.laubner.com<br \/>\nOnline Shop: https:\/\/www.laubner-shop.com\/de\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als renommiertes Systemhaus f\u00fcr Auto-ID Solutions sch\u00f6pft die Andreas Laubner GmbH mit Sitz in Maxdorf (RLP) aus \u00fcber 25 Jahren Erfahrung in den Branchen Logistik und Industrie. Jahrzehntelange enge Partnerschaften mit zahlreichen Kunden aus ganz Europa unterstreichen unsere umfassenden Kompetenzen. Wir passen unsere Leistungen und Services individuell an unsere Kunden an &#8211; bei uns gibt [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_api_id":"161313","_stand_number":"F04-4","_partner_id":"3sq2h5s9z85op","_package_code":"00-EASY-EASYGO25-300","_website":"https:\/\/www.laubner.com","_email":"r.lahlal@laubner.com","_facebook":"https:\/\/www.facebook.com\/andreaslaubnergmbh","_linkedin":"https:\/\/www.linkedin.com\/company\/andreas-laubner-gmbh","_twitter":"https:\/\/twitter.com\/LaubnerAutoID","_instagram":"https:\/\/www.instagram.com\/andreaslaubnergmbh\/","_zipcode":"67133","_town":"Maxdorf","_video_banner":"","_floorplan_url":"","footnotes":""},"edition":[431],"country":[93],"exhibitor-category":[435,437,438,436],"class_list":["post-52159","exhibitor","type-exhibitor","status-publish","hentry","edition-logistics-automation-dortmund-2024","country-de","exhibitor-category-automatisierungstechnik-17851","exhibitor-category-kennzeichnung-und-identifikation-17844","exhibitor-category-kommissionierungstechnik-17843","exhibitor-category-smart-logistics-17853","feature--stand-has-video-header","feature--stand-has-logo-shown"],"_logo":null,"_cover_image":null,"_thumbnail_id":null,"_products":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/54584"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/53071"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/53069"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/53070"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/53067"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/53068"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/53029"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/53030"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/53025"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/products\/53026"}],"_news":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/news\/54602"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/news\/54599"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/news\/53072"}],"_jobs":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/job\/54610"},{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/job\/54607"}],"_links":{"self":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/52159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor"}],"about":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/types\/exhibitor"}],"version-history":[{"count":3,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/52159\/revisions"}],"predecessor-version":[{"id":53020,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor\/52159\/revisions\/53020"}],"wp:attachment":[{"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/media?parent=52159"}],"wp:term":[{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/edition?post=52159"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/country?post=52159"},{"taxonomy":"exhibitor-category","embeddable":true,"href":"https:\/\/www.intralogistik-messen.de\/en\/wp-json\/wp\/v2\/exhibitor-category?post=52159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}